{"id":12699,"date":"2023-01-29T14:49:19","date_gmt":"2023-01-29T13:49:19","guid":{"rendered":"https:\/\/www.sngenealogie.ch\/wp\/?page_id=12699"},"modified":"2023-01-29T15:14:11","modified_gmt":"2023-01-29T14:14:11","slug":"les-double-noms","status":"publish","type":"page","link":"https:\/\/www.sngenealogie.ch\/wp\/bulletins\/bulletin-61\/les-double-noms\/","title":{"rendered":"Les double-noms"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12699\" class=\"elementor elementor-12699\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c184fb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c184fb4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c4f2430\" data-id=\"3c4f2430\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28a7be6c elementor-widget elementor-widget-heading\" data-id=\"28a7be6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Bulletin 61 \/ Octobre 2020<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64b397dc elementor-widget elementor-widget-heading\" data-id=\"64b397dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les doubles-noms<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-187d1c15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"187d1c15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6539d444\" data-id=\"6539d444\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8457048 elementor-widget elementor-widget-heading\" data-id=\"8457048\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">par Germain Hausmann<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7770b6 elementor-widget elementor-widget-spacer\" data-id=\"e7770b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d49286 elementor-widget elementor-widget-text-editor\" data-id=\"4d49286\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&rsquo;Onomastique des anciennes familles neuch\u00e2teloises se caract\u00e9rise certaines fois par la pr\u00e9sence de doubles noms, ce qui est assez rare dans le domaine francophone, sauf en Franche-Comt\u00e9. Tout s&rsquo;explique assez facilement si on fait l&rsquo;histoire des noms qui d\u00e9signaient les personnes au cours des \u00e2ges.<\/p><p>Au d\u00e9but du Moyen-Age, le nom de famille n&rsquo;existait pas. La masse des pr\u00e9noms \u00e9tait suffisamment vaste pour qu&rsquo;il n&rsquo;y ait pas deux homonymes au sein d&rsquo;une m\u00eame communaut\u00e9. Ces noms \u00e9taient la plupart d&rsquo;origine germanique et sans rapport avec la religion (par exemple cette liste datant de l&rsquo;an mil : Videmarus, Fredebundus, Gondeulfus, Agano, Teudemundus, Fredeboldus). Puis, l&rsquo;usage voulut que l&rsquo;on choisisse parmi les saints les noms de bapt\u00eame. Le choix se fit plus restreint, certains saints ont eu plus de succ\u00e8s que d&rsquo;autres et il y eu plusieurs Jean, plusieurs Pierre, etc. dans un village. Pour les diff\u00e9rencier, on commen\u00e7a par les nommer par un diminutif (par exemple Pierre devient Perroud, Perret, Porret, P\u00e9tremand, Perrenoud, etc. Jean devient Jeannot, Jeannet, Junod, Jeannier, Jeannerod, etc.), mais le syst\u00e8me atteint assez vite ses limites.<\/p><p>C&rsquo;est \u00e0 ce moment-l\u00e0 qu&rsquo;appara\u00eet le nom de famille (soit un nom h\u00e9r\u00e9ditaire). Dans le canton de Neuch\u00e2tel, cela commence vers 1250 dans le Val-de-Ruz par le nom de Cuche. Cela s&rsquo;\u00e9tend au reste du canton peu \u00e0 peu et l&rsquo;usage de la doublette pr\u00e9nom + nom se g\u00e9n\u00e9ralise et devient pr\u00e9pond\u00e9rant vers 1350. A noter que cette coutume touche toutes les couches de la population et concerne tant les nobles, les hommes libres et les serfs.<\/p><p>Mais, jusqu&rsquo;en 1500, l\u2019h\u00e9r\u00e9dit\u00e9 de ses patronymes n&rsquo;est pas toujours respect\u00e9e. Un fils peut porter un autre nom que son p\u00e8re. Un fils peut reprendre le nom de sa m\u00e8re (non de son p\u00e8re). Il y a l&rsquo;usage de double noms (s\u00e9par\u00e9s par alias ou dit) ce qui ne facilite pas le travail du g\u00e9n\u00e9alogiste : Pierre Dupont alias Durand est aussi cit\u00e9 sous les noms de Pierre Dupont, de Pierre Durand, de Pierre Durand dit Dupont ou m\u00eame de Pierre Dumoulin, suivant les textes. Le syst\u00e8me se met donc en place peu \u00e0 peu.<\/p><p>Vers 1500, notre fa\u00e7on de faire traditionnelle entre en vigueur, le nom devient strictement h\u00e9r\u00e9ditaire et se rapporte au patronyme du p\u00e8re uniquement. Aujourd&rsquo;hui, les nouvelles lois mettent \u00e0 mal ce syst\u00e8me.<\/p><p>Dans notre canton (surtout dans le Haut), la vari\u00e9t\u00e9 patronymique est assez restreinte, c&rsquo;est-\u00e0-dire qu&rsquo;il arrive assez souvent qu&rsquo;il y ait au sein d&rsquo;un village plusieurs homonymes (pr\u00e9nom + nom de famille \u00e9gaux). Voil\u00e0 pourquoi, certaines branches portent un deuxi\u00e8me nom de famille. Ainsi, dans la famille Robert que je connais bien, il y a 1) des Robert, 2) des Robert-Nicoud, 3) des Robert-Tissot, 4) des Robert-Grandpierre, 5) des Robert-Charrue, 6) des Robert-Laurent, 7) des Robert-Dayon et des 8) Othenin-Robert. La famille Matthey se divise en 1) Matthey, 2) Matthey-Claudet, 3) Matthey-de-l&rsquo;Endroit, 4) Matthey-de-l&rsquo;Etang, 5) Matthey-des-Bornels, 6) Matthey-Doret, 7) Matthey-Dupraz, 8) Matthey-Guenet, 9) Matthey-Henry, 10) Matthey-Jaquet, 11) Matthey-Jeantet, 12) Matthey-Jonais, 13) Matthey-Junod, 14) Matthey-Petit-Abram et 15) Matthey-Pierret. Ces patronymes doubles sont assez caract\u00e9ristiques du Jura neuch\u00e2telois. Sous l\u2019Ancien R\u00e9gime, lorsqu\u2019un membre de ses familles \u00e0 double patronyme quittait la r\u00e9gion o\u00f9 ces doublons avaient leur utilit\u00e9 de diff\u00e9renciation, il a tendance \u00e0 perdre son deuxi\u00e8me patronyme. Ainsi, les Robert-Nicoud qui s\u2019installent dans la r\u00e9gion de Noiraigue (o\u00f9 ils sont seuls \u00e0 porter ce nom) redeviennent des Robert tout court. Il donneront leur nom \u00e0 la ferme qu&rsquo;ils occupaient, la ferme Robert au Creux-du-Vent. Dans d&rsquo;autres r\u00e9gion, par exemple aux Verri\u00e8res, la plupart de ces double-noms ne sont pas repris par l&rsquo;\u00e9tat civil et ont disparu. Il faut aussi noter que l&rsquo;arriv\u00e9e de l&rsquo;\u00c9tat moderne a s\u00e9v\u00e8rement restreint l&rsquo;utilisation de ces noms \u00e0 rallonge.<\/p><p>Il y a encore une autre cause: certaines familles qui se terminent en quenouille demandent \u00e0 leur beau-fils de reprendre leur nom pour qu&rsquo;il subsiste au cours des g\u00e9n\u00e9rations futures. Cela concerne des familles notables bourgeoises de Neuch\u00e2tel, telle que les de Tribolet-Hardy, issus d&rsquo;un M. Tribolet qui \u00e9pousa une demoiselle Hardy, derni\u00e8re de sa branche.<\/p><p>En voici la liste pour le canton pour les familles subsistantes:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56e273d elementor-widget elementor-widget-heading\" data-id=\"56e273d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">HAUT DU CANTON<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e9f931 elementor-widget elementor-widget-text-editor\" data-id=\"9e9f931\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Familles des Brenets<\/h4><p>Famille Billon: Claudot-Billon.<br \/>Famille Guinand: Guinand-Samson.<br \/>Famille Jeanmaire (voir famille Quartier).<br \/>Famille Quartier: Cartier, Jean-Cartier, Jeanmaire (issue des Quartier-dit-Maire), Jeanmaire-dit-Cartier, Jeanmaire-dit-Quartier, Jeanquartier, Quartier-dit-Maire, Quartier-la-Tente.<\/p><h4>Famille du Cerneux-P\u00e9quignot<\/h4><p><em> (il s&rsquo;agit donc de familles d\u2019origine franc-comtoise)<\/em><br \/>Famille Vermot: Simon-Vermot, Vermot-Gaud, Vermot-Gros-Huguenin, Vermot-Petit-Outhenin.<\/p><h4>Familles du Locle<\/h4><p>Famille Besancenet: P\u00e9tremand-Besancenet.<br \/>Famille Brandt: Brandt-dit-Grieurin, Brandt-dit-Sim\u00e9on.<br \/>Famille Calame: Calame-dit-Barbier, Calame-Longjean, Calame-Rosset.<br \/>Famille Courvoisier: Courvoisier-Cl\u00e9ment, Courvoisier-dit-Voisin, Courvoisier-Piot.<br \/>Famille Delachaux: Delachaux-dit-Gay, Delachaux-dit-Peter.<br \/>Famille Droz: Amez-Droz, Droz-dit-Busset, Droz-Georget, Humbert-Droz,<br \/>Humbert-Droz-dit-Walter, Humbert-Droz-Laurent, Humbert-Prince.<br \/>Famille Dubois: DuBois, Dubois-dit-Bonclaude, Dubois-dit-Cosandier, Dubois-<br \/>Franck.<br \/>Famille Ducommun: Ducommun-dit-Boudry, Ducommun-dit-Tinnon, Ducom\u00acmun-dit-Verron, Ducommun-Petit-Comp\u00e8re.<br \/>Famille Dumont: Dumont-dit-Vieiljean, Dumont-dit-Voitel.<br \/>Famille Favre: Faure, Favre-Brandt, Favre-dit-Jean-Favre, Favre-dit-Jeanfavre, Favre-Leuba, Jeanfavre (NB.: la famille <em>Favre-Bulle<\/em> est un cas particulier, car elle provient de France et pour qu\u2019elle ne se confonde avec les <em>Favre<\/em> neuch\u00e2telois, on a ajout\u00e9 \u00e0 son patronyme le nom de son lieu d\u2019origine, Bulle en France dans le Doubs).<br \/>Famille Gentil: Perret-Gentil, Perret-Gentil-dit-Maillard.<br \/>Famille Girard: Othenin-Girard.<br \/>Famille Huguenin: Huguenin-Bergenat, Huguenin-Dezot, Huguenin-dit-Benjamin, Huguenin-dit-Lenoir, Huguenin-Dumittan, Huguenin-Elie, Huguenin-L&rsquo;Hardy, Huguenin-Richard, Huguenin-Virchaux, Huguenin-Vuillemenet, Huguenin-Vuillemin.<br \/>Famille Humbert-Prince (voir ci-dessus <em>Droz<\/em>)<br \/>Famille Jacot: Jacot-Baron, Jacot-Descombes, Jacot-Descombes-dit-Gendre.<br \/>Famille Jeanneret: Jeanneret-de-la-Coudre, Jeanneret-Gris, Jeanneret-Grosjean, Perret-Jeanneret.<br \/>Famille Matthey: Matthey-Claudet, Matthey-de-l\u2019Endroit, Matthey-de-l\u2019Etang, Matthey-dit-des-Bornels, Matthey-Doret (d\u2019o\u00f9 une famille <em>Doret<\/em> vaudoise), Matthey-Dupraz, Matthey-Guenet, Matthey-Henry, Matthey-Jaquet, Matthey-Jeantet, Matthey-Jonais, Matthey-Junod, Matthey-Petit-Abram, Matthey-Pierret.<br \/>Famille Montandon: Jacot-dit-Montandon, Montandon-Allemand, Montandon-Blaiselion, Montandon-Clerc, Montandon-Girard, Montandon-la-Longe, Montandon-Varoda.<br \/>Famille Robert: Othenin-Robert, Robert-Charrue, Robert-Dayon, Robert-<br \/>Grandpierre, Robert-Laurent, Robert-Nicoud, Robert-Rose, Robert-Tissot.<br \/>Famille Sandoz: Sandol-Roy (de), Sandoz-Bragard, Sandoz-Gendre, Sandoz-Longjean, Sandoz-Otheneret, Sandoz-Othenin.<br \/>Famille Savoie: M\u00e9lanjoie-dit-Savoie.<br \/>Famille Tissot: Tissot-Daguette.<\/p><h4>Familles de La Sagne<\/h4><p>Famille Benoit: Benoit-dit-Rouiller (cette famille descend d\u2019un enfant naturel qui porta successivement le nom de ses p\u00e8re et m\u00e8re).<br \/>Famille Comtesse: Contesse, P\u00e9ter-Comtesse (d\u2019o\u00f9 une famille <em>Petter<\/em> vaudoise) (en fait la famille <em>Comtesse<\/em> est une branche de la famille <em>Perrenoud<\/em>).<br \/>Famille Gentil: Guillaume-Gentil.<br \/>Famille Guillarmod: Jacot-Guillarmod.<br \/>Famille Mairet: Jean-Mairet.<br \/>Famille Matile: Jean-Petit-Matile.<br \/>Famille Nicolet: Nicolet-dit-Favre, Nicolet-dit-F\u00e9lix, Nicolet-Monnier.<br \/>Famille Perrenoud: Perrenod-dit-Pernod, Pernod, Grand-Guillaume-Perrenoud, Grandjean-Perrenoud-Comtesse, Perrenoud-Andr\u00e9, Perrenoud-Favre, Perrenoud-Jeanneret, Perrenoud-le-Favre.<br \/>Famille Pr\u00e9vot: Matthey-Pr\u00e9vot.<br \/>Famille Richard: Jean-Richard, Jean-Richard-dit-Bressel (autrefois appel\u00e9e simplement Bressel), Jeanrichard-dit-Bressel.<br \/>Famille Tissot: Tissot-Vougeux.<br \/>Famille Tochenet: Grospierre-Tochenet.<br \/>Famille Vuille: Vuille-Bille, Vuille-dit-Bille, Vuille-dit-Wille, Wille (il s\u2019agit ici surtout de changement dans la prononciation de ce nom).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4aacb1 elementor-widget elementor-widget-heading\" data-id=\"c4aacb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VAL DE RUZ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b188fd8 elementor-widget elementor-widget-text-editor\" data-id=\"b188fd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Famille de Boudevilliers<\/h4><p>Famille Bille: Girardbille.<\/p><h4>Famille de Cernier<\/h4><p>Famille Soguel: Soguel-dit-Picard, Soguel-dit-Piquard<\/p><h4>Famille de Ch\u00e9zard-Saint-Martin<\/h4><p>Famille Berthoud: Berthoud-dit-Gallon.<\/p><h4>Famille de Fontainemelon<\/h4><p>Famille Benguerel: Benguerel-dit-Jacot, Benguerel-dit-Perroud.<\/p><h4>Famille des Geneveys-sur-Coffrane<\/h4><p>Famille Perregaux: Perregaux-Dielf.<\/p><h4>Famille de Saules<\/h4><p>Famille Dessaules: Dessaules-dit-Duneuf<\/p><h4>Famille de Savagnier<\/h4><p>Famille Jeanperrin.<\/p><h4>Famille de Valangin<\/h4><p>Famille Tissot: Tissot-dit-Choppia, Tissot-dit-Sanfin.<\/p><h4>Famille de Villiers<\/h4><p>Famille Dubois: Dubois-Reymond (Le patronyme Dubois est associ\u00e9 au XIX\u00e8me si\u00e8cle au matronyme Reymond).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11aaa6f elementor-widget elementor-widget-heading\" data-id=\"11aaa6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">VAL DE TRAVERS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1897498 elementor-widget elementor-widget-text-editor\" data-id=\"1897498\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Famille du Petit Bayard<\/h4><p>Famille Guye: Guye-Bergeret, Guye-Vuill\u00e8me (A noter que la famille Contre-Guye, signal\u00e9e dans quelques ouvrages, n\u2019a exist\u00e9 que le temps d\u2019un mariage).<\/p><h4>Familles du Grand Bayard<\/h4><p>Famille Piaget: Piaget-Rossel.<br \/>Famille Reymond: Reymond-Jubin.<br \/>Famille Rosselet: Rosselet-Christ, Rosselet-Droux, Rosselet-Jordan, Rosselet-Petit Jaques.<\/p><h4>Familles de Belleperche<\/h4><p>Famille Bolle: Bolle-Picard.<br \/>Famille Redard: Redard-Jacot.<br \/>Famille Robert: Robert-Prince.<\/p><h4>Famille de Saint-Sulpice<\/h4><p>Famille Lambelet: Lambelet-du-Gay.<\/p><h4>Famille de Buttes<\/h4><p>Famille Leuba: Leuba-Bastillon, Leuba-dit-Galland, Leubaz.<\/p><h4>Familles de Fleurier<\/h4><p>Famille Berthoud: Berthoud-Esa\u00efe.<br \/>Famille Vaucher: Vaucher de la Croix, Vaucher-Joset.<\/p><h4>Familles de M\u00f4tiers<\/h4><p>Famille Boy de la Tour.<br \/>Famille Dubois: Dubois-dit du-Terreaux (cette famille descend d\u2019un enfant ill\u00e9gitime d\u2019un Monsieur du Terreaux, de M\u00f4tiers, et d\u2019une demoiselle Dubois, de Buttes).<br \/>Famille Jeanrenaud.<\/p><h4>Familles de Couvet<\/h4><p>Famille Borel: Borel-Jaquet, Borel-Petit-Jaquet, Borel-Petit-Jean, Borel-Saladin.<br \/>Famille Jeanjaquet.<br \/>Famille Petitpierre: Petitpierre-chez-Jean.<\/p><h4>Familles de Travers<\/h4><p>Famille Dubois: Dubois-Dunilach (nous ne connaissons pas leur parent\u00e9 avec les du Bois de Dunilac, de M\u00f4tiers,, et les Dubois du Nilac, de Buttes).<br \/>Famille Greset: Greset-dit-Grisel (on a mis ensemble de deux orthographes du m\u00eame nom), Grezet, Grizel.<br \/>Famille Perrinjaquet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bce092d elementor-widget elementor-widget-heading\" data-id=\"bce092d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">BAS DU CANTON<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07f14f4 elementor-widget elementor-widget-text-editor\" data-id=\"07f14f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Famille d&rsquo;Auvernier<\/h4><p>Famille Mayor: Mayor-dit-Beaujon.<\/p><h4>Famille de B\u00f4le<\/h4><p>Famille Jeanjaquet.<\/p><h4>Famille d&rsquo;Epagnier<\/h4><p>Famille Decreuze-dit-Dupoil.<\/p><h4>Famille de Fresens<\/h4><p>Famille Gacon: Gaccon, Gacon-dit-Car\u00eame.<\/p><h4>Famille de Marin<\/h4><p>Famille Jeanhenry.<\/p><h4>Familles de Montalchez<\/h4><p>Famille Burgat: Burgat-dit-Grellet.<br \/>Famille Rognon: Rognon-Florian.<\/p><h4>Familles de Neuch\u00e2tel<\/h4><p>Famille Menoud-dit-Gendre.<br \/>Famille Pourtal\u00e8s: Pourtal\u00e8s-Marcet (de).<br \/>Famille Richard: Richard dit Leschery.<br \/>Famille Tribolet: Tribolet-Hardy (de).<\/p><h4>Famille de Rochefort<\/h4><p>Famille Renaud: Renaud dit de l\u2019H\u00f4tel Neuf, Renaud-dit-Louis.<\/p><h4>Famille de Saint-Blaise<\/h4><p>Famille Prince: Prince-dit-Clottu.<\/p><h4>Famille de Sauges<\/h4><p>Famille Pierrehumbert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-394a1564 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"394a1564\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2e538c5c\" data-id=\"2e538c5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-824257a elementor-widget elementor-widget-button\" data-id=\"824257a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.sngenealogie.ch\/wp\/bulletins\/bulletin-61\/chronique-familiale-carlo-rossinelli\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-left\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Article pr\u00e9c\u00e9dent<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-99cc7f\" data-id=\"99cc7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7414bc44 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7414bc44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.sngenealogie.ch\/wp\/bulletins\/bulletin-61\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-up\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Bulletin 61<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35e0edd6\" data-id=\"35e0edd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bulletin 61 \/ Octobre 2020 Les doubles-noms par Germain Hausmann L&rsquo;Onomastique des anciennes familles neuch\u00e2teloises se caract\u00e9rise certaines fois par [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2365,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"wf_page_folders":[87],"class_list":["post-12699","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/pages\/12699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/comments?post=12699"}],"version-history":[{"count":7,"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/pages\/12699\/revisions"}],"predecessor-version":[{"id":12719,"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/pages\/12699\/revisions\/12719"}],"up":[{"embeddable":true,"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/pages\/2365"}],"wp:attachment":[{"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/media?parent=12699"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/www.sngenealogie.ch\/wp\/wp-json\/wp\/v2\/wf_page_folders?post=12699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}